{"id":84,"count":1,"description":"Bienvenido al destino del vapeo de alta capacidad. El <strong>Vapeador Puff 9K (9000 caladas)<\/strong> ha sido dise\u00f1ada espec\u00edficamente para los vapeadores frecuentes que est\u00e1n cansados de sustituir constantemente los dispositivos de corta duraci\u00f3n y exigen una experiencia ininterrumpida de primera calidad.\r\n\r\nCargados con una enorme reserva de e-l\u00edquido, estos dispositivos est\u00e1n hechos para recorrer largas distancias. Seleccionamos cuidadosamente s\u00f3lo las mejores marcas mundiales para nuestro inventario. Esto garantiza que cada <strong>9000-puff<\/strong> que elijas ofrece una bater\u00eda fiable, una producci\u00f3n de vapor constante y un sabor excepcional desde la primera calada hasta la \u00faltima.","link":"https:\/\/tovanvape.com\/es\/product-category\/different-puffs-of-disposable-vapes\/puff-9k\/","name":"Puff 9K","slug":"puff-9k","taxonomy":"product_cat","parent":82,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/tovanvape.com\/es\/wp-json\/wp\/v2\/product_cat\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tovanvape.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/tovanvape.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/tovanvape.com\/es\/wp-json\/wp\/v2\/product_cat\/82"}],"wp:post_type":[{"href":"https:\/\/tovanvape.com\/es\/wp-json\/wp\/v2\/product?product_cat=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}